{"id":28711,"date":"2023-10-04T16:43:54","date_gmt":"2023-10-04T16:43:54","guid":{"rendered":"https:\/\/www.ikiam.edu.ec\/?post_type=docs&amp;p=28711"},"modified":"2023-10-04T16:43:54","modified_gmt":"2023-10-04T16:43:54","password":"","slug":"fortalecimiento-de-la-cadena-de-valor-en-las-comunidades-y-organizaciones-relacionadas-a-la-produccion-y-comercializacion-de-theobroma-bicolor-en-la-provincia-del-napo","status":"publish","type":"docs","link":"https:\/\/www.ikiam.edu.ec\/index.php\/docs\/fortalecimiento-de-la-cadena-de-valor-en-las-comunidades-y-organizaciones-relacionadas-a-la-produccion-y-comercializacion-de-theobroma-bicolor-en-la-provincia-del-napo\/","title":{"rendered":"Fortalecimiento de la cadena de valor en las comunidades y organizaciones relacionadas a la producci\u00f3n y comercializaci\u00f3n de Theobroma bicolor en la provincia del Napo"},"content":{"rendered":"<div class=\"wp-block-pdfemb-pdf-embedder-viewer\"><a href=\"https:\/\/www.ikiam.edu.ec\/wp-content\/uploads\/2023\/10\/Infograma_cadena-valor-Theobroma-Franklin-Sanchez.pptx.pdf\" class=\"pdfemb-viewer\" style=\"\" data-width=\"max\" data-height=\"max\" data-toolbar=\"bottom\" data-toolbar-fixed=\"off\">Infograma_cadena-valor-Theobroma-Franklin-Sanchez.pptx<\/a><\/div>\n<p class=\"wp-block-pdfemb-pdf-embedder-viewer\"><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"doc_category":[191],"doc_tag":[43],"class_list":["post-28711","docs","type-docs","status-publish","hentry","doc_category-proyectos","doc_tag-43"],"year_month":"2026-07","word_count":0,"total_views":0,"reactions":{"happy":0,"normal":0,"sad":0},"author_info":{"name":"Wendy Enriquez","author_nicename":"wendy-enriquezikiam-edu-ec","author_url":"https:\/\/www.ikiam.edu.ec\/index.php\/author\/wendy-enriquezikiam-edu-ec\/"},"doc_category_info":[{"term_name":"Proyectos","term_url":"https:\/\/www.ikiam.edu.ec\/index.php\/docs-category\/proyectos\/"}],"doc_tag_info":[{"term_name":"2023","term_url":"https:\/\/www.ikiam.edu.ec\/index.php\/docs-tag\/2023\/"}],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fortalecimiento de la cadena de valor en las comunidades y organizaciones relacionadas a la producci\u00f3n y comercializaci\u00f3n de Theobroma bicolor en la provincia del Napo - Universidad Regional Amaz\u00f3nica Ikiam<\/title>\n<meta name=\"description\" content=\"Documento del proyecto &quot;Fortalecimiento de la cadena de valor en las comunidades y organizaciones...&quot; diirector del proyecto Franklin S\u00e1nchez.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ikiam.edu.ec\/index.php\/docs\/fortalecimiento-de-la-cadena-de-valor-en-las-comunidades-y-organizaciones-relacionadas-a-la-produccion-y-comercializacion-de-theobroma-bicolor-en-la-provincia-del-napo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fortalecimiento de la cadena de valor en las comunidades y organizaciones relacionadas a la producci\u00f3n y comercializaci\u00f3n de Theobroma bicolor en la provincia del Napo - Universidad Regional Amaz\u00f3nica Ikiam\" \/>\n<meta property=\"og:description\" content=\"Documento del proyecto &quot;Fortalecimiento de la cadena de valor en las comunidades y organizaciones...&quot; diirector del proyecto Franklin S\u00e1nchez.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ikiam.edu.ec\/index.php\/docs\/fortalecimiento-de-la-cadena-de-valor-en-las-comunidades-y-organizaciones-relacionadas-a-la-produccion-y-comercializacion-de-theobroma-bicolor-en-la-provincia-del-napo\/\" \/>\n<meta property=\"og:site_name\" content=\"Universidad Regional Amaz\u00f3nica Ikiam\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/IkiamOficial\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@u_ikiam\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ikiam.edu.ec\/index.php\/docs\/fortalecimiento-de-la-cadena-de-valor-en-las-comunidades-y-organizaciones-relacionadas-a-la-produccion-y-comercializacion-de-theobroma-bicolor-en-la-provincia-del-napo\/\",\"url\":\"https:\/\/www.ikiam.edu.ec\/index.php\/docs\/fortalecimiento-de-la-cadena-de-valor-en-las-comunidades-y-organizaciones-relacionadas-a-la-produccion-y-comercializacion-de-theobroma-bicolor-en-la-provincia-del-napo\/\",\"name\":\"Fortalecimiento de la cadena de valor en las comunidades y organizaciones relacionadas a la producci\u00f3n y comercializaci\u00f3n de Theobroma bicolor en la provincia del Napo - Universidad Regional Amaz\u00f3nica Ikiam\",\"isPartOf\":{\"@id\":\"https:\/\/www.ikiam.edu.ec\/#website\"},\"datePublished\":\"2023-10-04T16:43:54+00:00\",\"description\":\"Documento del proyecto \\\"Fortalecimiento de la cadena de valor en las comunidades y organizaciones...\\\" diirector del proyecto Franklin S\u00e1nchez.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ikiam.edu.ec\/index.php\/docs\/fortalecimiento-de-la-cadena-de-valor-en-las-comunidades-y-organizaciones-relacionadas-a-la-produccion-y-comercializacion-de-theobroma-bicolor-en-la-provincia-del-napo\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ikiam.edu.ec\/index.php\/docs\/fortalecimiento-de-la-cadena-de-valor-en-las-comunidades-y-organizaciones-relacionadas-a-la-produccion-y-comercializacion-de-theobroma-bicolor-en-la-provincia-del-napo\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ikiam.edu.ec\/index.php\/docs\/fortalecimiento-de-la-cadena-de-valor-en-las-comunidades-y-organizaciones-relacionadas-a-la-produccion-y-comercializacion-de-theobroma-bicolor-en-la-provincia-del-napo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"La Universidad\",\"item\":\"https:\/\/www.ikiam.edu.ec\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Documentaci\u00f3n\",\"item\":\"https:\/\/www.ikiam.edu.ec\/index.php\/docs\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Fortalecimiento de la cadena de valor en las comunidades y organizaciones relacionadas a la producci\u00f3n y comercializaci\u00f3n de Theobroma bicolor en la provincia del Napo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ikiam.edu.ec\/#website\",\"url\":\"https:\/\/www.ikiam.edu.ec\/\",\"name\":\"Universidad Regional Amaz\u00f3nica Ikiam\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.ikiam.edu.ec\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ikiam.edu.ec\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.ikiam.edu.ec\/#organization\",\"name\":\"Universidad Regional Amaz\u00f3nica Ikiam\",\"url\":\"https:\/\/www.ikiam.edu.ec\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.ikiam.edu.ec\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ikiam.edu.ec\/wp-content\/uploads\/2021\/12\/logo-ikiam-1.png\",\"contentUrl\":\"https:\/\/www.ikiam.edu.ec\/wp-content\/uploads\/2021\/12\/logo-ikiam-1.png\",\"width\":210,\"height\":90,\"caption\":\"Universidad Regional Amaz\u00f3nica Ikiam\"},\"image\":{\"@id\":\"https:\/\/www.ikiam.edu.ec\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/IkiamOficial\/\",\"https:\/\/x.com\/u_ikiam\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fortalecimiento de la cadena de valor en las comunidades y organizaciones relacionadas a la producci\u00f3n y comercializaci\u00f3n de Theobroma bicolor en la provincia del Napo - Universidad Regional Amaz\u00f3nica Ikiam","description":"Documento del proyecto \"Fortalecimiento de la cadena de valor en las comunidades y organizaciones...\" diirector del proyecto Franklin S\u00e1nchez.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ikiam.edu.ec\/index.php\/docs\/fortalecimiento-de-la-cadena-de-valor-en-las-comunidades-y-organizaciones-relacionadas-a-la-produccion-y-comercializacion-de-theobroma-bicolor-en-la-provincia-del-napo\/","og_locale":"es_ES","og_type":"article","og_title":"Fortalecimiento de la cadena de valor en las comunidades y organizaciones relacionadas a la producci\u00f3n y comercializaci\u00f3n de Theobroma bicolor en la provincia del Napo - Universidad Regional Amaz\u00f3nica Ikiam","og_description":"Documento del proyecto \"Fortalecimiento de la cadena de valor en las comunidades y organizaciones...\" diirector del proyecto Franklin S\u00e1nchez.","og_url":"https:\/\/www.ikiam.edu.ec\/index.php\/docs\/fortalecimiento-de-la-cadena-de-valor-en-las-comunidades-y-organizaciones-relacionadas-a-la-produccion-y-comercializacion-de-theobroma-bicolor-en-la-provincia-del-napo\/","og_site_name":"Universidad Regional Amaz\u00f3nica Ikiam","article_publisher":"https:\/\/www.facebook.com\/IkiamOficial\/","twitter_card":"summary_large_image","twitter_site":"@u_ikiam","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ikiam.edu.ec\/index.php\/docs\/fortalecimiento-de-la-cadena-de-valor-en-las-comunidades-y-organizaciones-relacionadas-a-la-produccion-y-comercializacion-de-theobroma-bicolor-en-la-provincia-del-napo\/","url":"https:\/\/www.ikiam.edu.ec\/index.php\/docs\/fortalecimiento-de-la-cadena-de-valor-en-las-comunidades-y-organizaciones-relacionadas-a-la-produccion-y-comercializacion-de-theobroma-bicolor-en-la-provincia-del-napo\/","name":"Fortalecimiento de la cadena de valor en las comunidades y organizaciones relacionadas a la producci\u00f3n y comercializaci\u00f3n de Theobroma bicolor en la provincia del Napo - Universidad Regional Amaz\u00f3nica Ikiam","isPartOf":{"@id":"https:\/\/www.ikiam.edu.ec\/#website"},"datePublished":"2023-10-04T16:43:54+00:00","description":"Documento del proyecto \"Fortalecimiento de la cadena de valor en las comunidades y organizaciones...\" diirector del proyecto Franklin S\u00e1nchez.","breadcrumb":{"@id":"https:\/\/www.ikiam.edu.ec\/index.php\/docs\/fortalecimiento-de-la-cadena-de-valor-en-las-comunidades-y-organizaciones-relacionadas-a-la-produccion-y-comercializacion-de-theobroma-bicolor-en-la-provincia-del-napo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ikiam.edu.ec\/index.php\/docs\/fortalecimiento-de-la-cadena-de-valor-en-las-comunidades-y-organizaciones-relacionadas-a-la-produccion-y-comercializacion-de-theobroma-bicolor-en-la-provincia-del-napo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ikiam.edu.ec\/index.php\/docs\/fortalecimiento-de-la-cadena-de-valor-en-las-comunidades-y-organizaciones-relacionadas-a-la-produccion-y-comercializacion-de-theobroma-bicolor-en-la-provincia-del-napo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"La Universidad","item":"https:\/\/www.ikiam.edu.ec\/"},{"@type":"ListItem","position":2,"name":"Documentaci\u00f3n","item":"https:\/\/www.ikiam.edu.ec\/index.php\/docs\/"},{"@type":"ListItem","position":3,"name":"Fortalecimiento de la cadena de valor en las comunidades y organizaciones relacionadas a la producci\u00f3n y comercializaci\u00f3n de Theobroma bicolor en la provincia del Napo"}]},{"@type":"WebSite","@id":"https:\/\/www.ikiam.edu.ec\/#website","url":"https:\/\/www.ikiam.edu.ec\/","name":"Universidad Regional Amaz\u00f3nica Ikiam","description":"","publisher":{"@id":"https:\/\/www.ikiam.edu.ec\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ikiam.edu.ec\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.ikiam.edu.ec\/#organization","name":"Universidad Regional Amaz\u00f3nica Ikiam","url":"https:\/\/www.ikiam.edu.ec\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ikiam.edu.ec\/#\/schema\/logo\/image\/","url":"https:\/\/www.ikiam.edu.ec\/wp-content\/uploads\/2021\/12\/logo-ikiam-1.png","contentUrl":"https:\/\/www.ikiam.edu.ec\/wp-content\/uploads\/2021\/12\/logo-ikiam-1.png","width":210,"height":90,"caption":"Universidad Regional Amaz\u00f3nica Ikiam"},"image":{"@id":"https:\/\/www.ikiam.edu.ec\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/IkiamOficial\/","https:\/\/x.com\/u_ikiam"]}]}},"_links":{"self":[{"href":"https:\/\/www.ikiam.edu.ec\/index.php\/wp-json\/wp\/v2\/docs\/28711","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ikiam.edu.ec\/index.php\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/www.ikiam.edu.ec\/index.php\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/www.ikiam.edu.ec\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ikiam.edu.ec\/index.php\/wp-json\/wp\/v2\/comments?post=28711"}],"version-history":[{"count":0,"href":"https:\/\/www.ikiam.edu.ec\/index.php\/wp-json\/wp\/v2\/docs\/28711\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.ikiam.edu.ec\/index.php\/wp-json\/wp\/v2\/media?parent=28711"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/www.ikiam.edu.ec\/index.php\/wp-json\/wp\/v2\/doc_category?post=28711"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/www.ikiam.edu.ec\/index.php\/wp-json\/wp\/v2\/doc_tag?post=28711"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}